{"id":25773,"date":"2026-07-14T11:47:42","date_gmt":"2026-07-14T09:47:42","guid":{"rendered":"https:\/\/hardstamps.com\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/"},"modified":"2026-07-16T12:43:24","modified_gmt":"2026-07-16T10:43:24","slug":"ladrillo-lacre-tradicional-500gr-burdeos","status":"publish","type":"product","link":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/","title":{"rendered":"Ladrillo de lacre tradicional 500gr. BURDEOS."},"content":{"rendered":"<p>El bloque est\u00e1 hecho de cera de lacre tradicional. Es un material duro con un acabado brillante. Para abrir el documento u objeto sellado, debe romperse. Es delicado y se romper\u00e1 si se env\u00eda por correo.<\/p>\n<p>Desarrollado con f\u00f3rmulas tradicionales de fabricaci\u00f3n de cera de lacre y un m\u00e9todo artesanal basado en materias primas naturales. La calidad final de nuestro producto permite una f\u00e1cil aplicaci\u00f3n y una fuerte adherencia a cualquier tipo de superficie.<\/p>\n<p>Peso: 500 g<br \/>\nRendimiento: Aprox. 100 sellos\/65 botellas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El bloque est\u00e1 hecho de cera de lacre tradicional. Es un material duro con un acabado brillante. Para abrir el documento u objeto sellado, debe romperse. Es delicado y se romper\u00e1 si se env\u00eda por correo. Desarrollado con f\u00f3rmulas tradicionales de fabricaci\u00f3n de cera de lacre y un m\u00e9todo artesanal basado en materias primas naturales. [&hellip;]<\/p>\n","protected":false},"featured_media":24908,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[388],"product_tag":[],"class_list":["post-25773","product","type-product","status-publish","has-post-thumbnail","product_cat-lacre-tradicional","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ladrillo de lacre tradicional 500gr. BURDEOS. - Hardstamps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ladrillo de lacre tradicional 500gr. BURDEOS. - Hardstamps\" \/>\n<meta property=\"og:description\" content=\"El bloque est\u00e1 hecho de cera de lacre tradicional. Es un material duro con un acabado brillante. Para abrir el documento u objeto sellado, debe romperse. Es delicado y se romper\u00e1 si se env\u00eda por correo. Desarrollado con f\u00f3rmulas tradicionales de fabricaci\u00f3n de cera de lacre y un m\u00e9todo artesanal basado en materias primas naturales. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/\" \/>\n<meta property=\"og:site_name\" content=\"Hardstamps\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OmellaGrabados\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-16T10:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/brique_cire_bourdeos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OmellaGrabados\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/\",\"name\":\"Ladrillo de lacre tradicional 500gr. BURDEOS. - Hardstamps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/brique_cire_bourdeos.jpg\",\"datePublished\":\"2026-07-14T09:47:42+00:00\",\"dateModified\":\"2026-07-16T10:43:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/brique_cire_bourdeos.jpg\",\"contentUrl\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/brique_cire_bourdeos.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/ladrillo-lacre-tradicional-500gr-burdeos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/comecar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/loja-carimbos-portugal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ladrillo de lacre tradicional 500gr. BURDEOS.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/\",\"name\":\"Hardstamps\",\"description\":\"Punzones y sellos personalizados para la industria y la artesan\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#organization\",\"name\":\"Hardstamps\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Untitled.png\",\"contentUrl\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Untitled.png\",\"width\":171,\"height\":85,\"caption\":\"Hardstamps\"},\"image\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OmellaGrabados\",\"https:\\\/\\\/x.com\\\/OmellaGrabados\",\"https:\\\/\\\/www.instagram.com\\\/omellagrabados\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ladrillo de lacre tradicional 500gr. BURDEOS. - Hardstamps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/","og_locale":"pt_PT","og_type":"article","og_title":"Ladrillo de lacre tradicional 500gr. BURDEOS. - Hardstamps","og_description":"El bloque est\u00e1 hecho de cera de lacre tradicional. Es un material duro con un acabado brillante. Para abrir el documento u objeto sellado, debe romperse. Es delicado y se romper\u00e1 si se env\u00eda por correo. Desarrollado con f\u00f3rmulas tradicionales de fabricaci\u00f3n de cera de lacre y un m\u00e9todo artesanal basado en materias primas naturales. [&hellip;]","og_url":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/","og_site_name":"Hardstamps","article_publisher":"https:\/\/www.facebook.com\/OmellaGrabados","article_modified_time":"2026-07-16T10:43:24+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/brique_cire_bourdeos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@OmellaGrabados","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/","url":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/","name":"Ladrillo de lacre tradicional 500gr. BURDEOS. - Hardstamps","isPartOf":{"@id":"https:\/\/hardstamps.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/#primaryimage"},"image":{"@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/#primaryimage"},"thumbnailUrl":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/brique_cire_bourdeos.jpg","datePublished":"2026-07-14T09:47:42+00:00","dateModified":"2026-07-16T10:43:24+00:00","breadcrumb":{"@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/#primaryimage","url":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/brique_cire_bourdeos.jpg","contentUrl":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/brique_cire_bourdeos.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/ladrillo-lacre-tradicional-500gr-burdeos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hardstamps.com\/pt-pt\/comecar\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/hardstamps.com\/pt-pt\/loja-carimbos-portugal\/"},{"@type":"ListItem","position":3,"name":"Ladrillo de lacre tradicional 500gr. BURDEOS."}]},{"@type":"WebSite","@id":"https:\/\/hardstamps.com\/pt-pt\/#website","url":"https:\/\/hardstamps.com\/pt-pt\/","name":"Hardstamps","description":"Punzones y sellos personalizados para la industria y la artesan\u00eda.","publisher":{"@id":"https:\/\/hardstamps.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hardstamps.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hardstamps.com\/pt-pt\/#organization","name":"Hardstamps","url":"https:\/\/hardstamps.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hardstamps.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/hardstamps.com\/wp-content\/uploads\/2024\/05\/Untitled.png","contentUrl":"https:\/\/hardstamps.com\/wp-content\/uploads\/2024\/05\/Untitled.png","width":171,"height":85,"caption":"Hardstamps"},"image":{"@id":"https:\/\/hardstamps.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OmellaGrabados","https:\/\/x.com\/OmellaGrabados","https:\/\/www.instagram.com\/omellagrabados\/"]}]}},"_links":{"self":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product\/25773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=25773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/media\/24908"}],"wp:attachment":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=25773"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=25773"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=25773"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=25773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}