{"id":25751,"date":"2026-07-14T11:47:47","date_gmt":"2026-07-14T09:47:47","guid":{"rendered":"https:\/\/hardstamps.com\/producto\/barra-lacre-tradicional-roja\/"},"modified":"2026-07-27T17:23:25","modified_gmt":"2026-07-27T15:23:25","slug":"barra-lacre-tradicional-roja","status":"publish","type":"product","link":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/","title":{"rendered":"Barra de lacre tradicional. ROJO."},"content":{"rendered":"<p>Barra grande de lacre rojo tradicional de alta calidad.<\/p>\n<p>El lacre tradicional es duro y fr\u00e1gil; se rompe al intentar abrir el sello, certificando as\u00ed que nadie lo ha manipulado.<\/p>\n<p>Este lacre se elabora artesanalmente en Espa\u00f1a con f\u00f3rmulas tradicionales y un m\u00e9todo completamente manual a partir de materias primas naturales. La calidad final de este producto Royal Lacre permite una f\u00e1cil aplicaci\u00f3n, una alta adherencia y un acabado muy brillante.<\/p>\n<p>Longitud: 18 cm.<br \/>\nPeso: 40 g.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barra grande de lacre rojo tradicional de alta calidad. El lacre tradicional es duro y fr\u00e1gil; se rompe al intentar abrir el sello, certificando as\u00ed que nadie lo ha manipulado. Este lacre se elabora artesanalmente en Espa\u00f1a con f\u00f3rmulas tradicionales y un m\u00e9todo completamente manual a partir de materias primas naturales. La calidad final de [&hellip;]<\/p>\n","protected":false},"featured_media":25026,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[388],"product_tag":[407,408],"class_list":["post-25751","product","type-product","status-publish","has-post-thumbnail","product_cat-lacre-tradicional","product_tag-barra-lacre","product_tag-barra-lacre-tradicional","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barra de lacre tradicional. ROJO. - Hardstamps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barra de lacre tradicional. ROJO. - Hardstamps\" \/>\n<meta property=\"og:description\" content=\"Barra grande de lacre rojo tradicional de alta calidad. El lacre tradicional es duro y fr\u00e1gil; se rompe al intentar abrir el sello, certificando as\u00ed que nadie lo ha manipulado. Este lacre se elabora artesanalmente en Espa\u00f1a con f\u00f3rmulas tradicionales y un m\u00e9todo completamente manual a partir de materias primas naturales. La calidad final de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/\" \/>\n<meta property=\"og:site_name\" content=\"Hardstamps\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OmellaGrabados\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-27T15:23:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/lacre_barra_TREDICIONAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OmellaGrabados\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/\",\"name\":\"Barra de lacre tradicional. ROJO. - Hardstamps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/lacre_barra_TREDICIONAL.jpg\",\"datePublished\":\"2026-07-14T09:47:47+00:00\",\"dateModified\":\"2026-07-27T15:23:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/lacre_barra_TREDICIONAL.jpg\",\"contentUrl\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/lacre_barra_TREDICIONAL.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/producto\\\/barra-lacre-tradicional-roja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/comecar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/loja-carimbos-portugal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barra de lacre tradicional. ROJO.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/\",\"name\":\"Hardstamps\",\"description\":\"Punzones y sellos personalizados para la industria y la artesan\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#organization\",\"name\":\"Hardstamps\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Untitled.png\",\"contentUrl\":\"https:\\\/\\\/hardstamps.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Untitled.png\",\"width\":171,\"height\":85,\"caption\":\"Hardstamps\"},\"image\":{\"@id\":\"https:\\\/\\\/hardstamps.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OmellaGrabados\",\"https:\\\/\\\/x.com\\\/OmellaGrabados\",\"https:\\\/\\\/www.instagram.com\\\/omellagrabados\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barra de lacre tradicional. ROJO. - Hardstamps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/","og_locale":"pt_PT","og_type":"article","og_title":"Barra de lacre tradicional. ROJO. - Hardstamps","og_description":"Barra grande de lacre rojo tradicional de alta calidad. El lacre tradicional es duro y fr\u00e1gil; se rompe al intentar abrir el sello, certificando as\u00ed que nadie lo ha manipulado. Este lacre se elabora artesanalmente en Espa\u00f1a con f\u00f3rmulas tradicionales y un m\u00e9todo completamente manual a partir de materias primas naturales. La calidad final de [&hellip;]","og_url":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/","og_site_name":"Hardstamps","article_publisher":"https:\/\/www.facebook.com\/OmellaGrabados","article_modified_time":"2026-07-27T15:23:25+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/lacre_barra_TREDICIONAL.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@OmellaGrabados","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/","url":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/","name":"Barra de lacre tradicional. ROJO. - Hardstamps","isPartOf":{"@id":"https:\/\/hardstamps.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/#primaryimage"},"image":{"@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/#primaryimage"},"thumbnailUrl":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/lacre_barra_TREDICIONAL.jpg","datePublished":"2026-07-14T09:47:47+00:00","dateModified":"2026-07-27T15:23:25+00:00","breadcrumb":{"@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/#primaryimage","url":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/lacre_barra_TREDICIONAL.jpg","contentUrl":"https:\/\/hardstamps.com\/wp-content\/uploads\/2026\/07\/lacre_barra_TREDICIONAL.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/hardstamps.com\/pt-pt\/producto\/barra-lacre-tradicional-roja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hardstamps.com\/pt-pt\/comecar\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/hardstamps.com\/pt-pt\/loja-carimbos-portugal\/"},{"@type":"ListItem","position":3,"name":"Barra de lacre tradicional. ROJO."}]},{"@type":"WebSite","@id":"https:\/\/hardstamps.com\/pt-pt\/#website","url":"https:\/\/hardstamps.com\/pt-pt\/","name":"Hardstamps","description":"Punzones y sellos personalizados para la industria y la artesan\u00eda.","publisher":{"@id":"https:\/\/hardstamps.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hardstamps.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hardstamps.com\/pt-pt\/#organization","name":"Hardstamps","url":"https:\/\/hardstamps.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hardstamps.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/hardstamps.com\/wp-content\/uploads\/2024\/05\/Untitled.png","contentUrl":"https:\/\/hardstamps.com\/wp-content\/uploads\/2024\/05\/Untitled.png","width":171,"height":85,"caption":"Hardstamps"},"image":{"@id":"https:\/\/hardstamps.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OmellaGrabados","https:\/\/x.com\/OmellaGrabados","https:\/\/www.instagram.com\/omellagrabados\/"]}]}},"_links":{"self":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product\/25751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=25751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/media\/25026"}],"wp:attachment":[{"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=25751"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=25751"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=25751"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hardstamps.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=25751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}